{"id":38323,"date":"2025-10-02T14:40:52","date_gmt":"2025-10-02T14:40:52","guid":{"rendered":"https:\/\/www.espaigirones.com\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/"},"modified":"2025-10-07T12:05:37","modified_gmt":"2025-10-07T12:05:37","slug":"guanya-packs-magma-i-visites-a-laquarium-oniria","status":"publish","type":"events","link":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/","title":{"rendered":"Gana packs Magma y visitas al acuario Oniria"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><u>BASES<\/u><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>1.Finalidad de la promoci\u00f3n<\/u><\/strong><\/p>\n<p>La presente promoci\u00f3n tiene por objeto incentivar las compras en los establecimientos del centro comercial Espai Giron\u00e8s mediante una campa\u00f1a de promoci\u00f3n de ventas. Para participar los visitantes deber\u00e1n entregar uno o dos tickets que sumen un m\u00ednimo de 40\u20ac en el Punto de Informaci\u00f3n para entrar en el sorteo de:<\/p>\n<ul>\n<li>4 packs para 2 personas con acceso al spa, masaje y una comida en el restaurante del centro l\u00fadico termal Magma de Santa Coloma de Farners<\/li>\n<li>2 visitas guiadas VIP para 4 personas por espacios interiores del Aquarium Oniria de Canet-en-Roussillon (sur de Francia)<\/li>\n<li>4 packs de entradas familiares (2 adultos + 2 ni\u00f1os o 2 adultos + 2 adultos) para el Aquarium Oniria de Canet-en-Roussillon (sur de Francia)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><u>2.Duraci\u00f3n de la promoci\u00f3n<\/u><\/strong><\/p>\n<p>La promoci\u00f3n se realizar\u00e1 en el per\u00edodo comprendido del 3 al 18 de octubre de 2025, ambos inclusive.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>3.Premios<\/u><\/strong><\/p>\n<p><strong>Habr\u00e1 2 sorteos<\/strong> durante el tiempo que dure la promoci\u00f3n. En cada uno de ellos se sortear\u00e1, entre todas las personas que hayan presentado uno o dos tickets que sumen un m\u00ednimo de 40\u20ac esa semana, los siguientes premios: 2 packs para 2 personas con acceso al spa, masaje y una comida en el restaurante del centro l\u00fadico termal Magma de Santa Coloma de Farners, 1 visita guiada VIP para 4 personas por espacios interiores del Aquarium Oniria de Canet-en-Roussillon (sur de Francia) y 2 packs de entradas familiares (2 adultos + 2 ni\u00f1os o 2 adultos + 2 adultos) para el Aquarium Oniria de Canet-en-Roussillon (sur de Francia).<\/p>\n<p>Los sorteos se har\u00e1n a trav\u00e9s de una aplicaci\u00f3n inform\u00e1tica y aleatoria los d\u00edas 13 y 20 de octubre. Se contactar\u00e1 directamente con los\/las ganadores\/as para acordar la entrega del premio, que se har\u00e1 en las oficinas del centro comercial.<\/p>\n<p>Una misma persona podr\u00e1 participar tantas veces como lo desee, siempre que presente cada vez uno o dos tickets de compra que sumen un m\u00ednimo de 40\u20ac, y siempre que sea dentro del per\u00edodo de la promoci\u00f3n (del 3 al 18 de octubre de 2025).<\/p>\n<p>En ning\u00fan caso el Centro Comercial sustituir\u00e1 el premio, a petici\u00f3n del ganador, por otro regalo diferente al previsto, o por su valor en met\u00e1lico.<\/p>\n<p>El Centro Comercial se reserva el derecho a sustituir el premio por otro en el caso que por causa de fuerza mayor \u00e9ste no pudiera ser entregado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>4.\u00c1mbito geogr\u00e1fico<\/u><\/strong><\/p>\n<p>La promoci\u00f3n tendr\u00e1 \u00e1mbito local en Catalu\u00f1a.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>5.\u00c1mbito personal<\/u><\/strong><\/p>\n<p>Tendr\u00e1n derecho a participar en la presente promoci\u00f3n todos los clientes y visitantes del Centro Comercial <strong>mayores de 18 a\u00f1os<\/strong>, quedando excluida completamente la participaci\u00f3n de trabajadores del Centro Comercial y menores.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>6.Funcionamiento de la promoci\u00f3n<\/u><\/strong><\/p>\n<p>La participaci\u00f3n en la promoci\u00f3n se realizar\u00e1 mediante la presentaci\u00f3n de uno o dos tickets que sumen un m\u00ednimo de 40\u20ac correspondientes a las compras realizadas en el Centro Comercial, junto a los productos comprados. Dichos tickets tendr\u00e1n que ser presentados en el Punto de Informaci\u00f3n del Centro Comercial que se halla situado en la planta baja, y deber\u00e1n corresponder a compras realizadas en tiendas o establecimientos del Centro Comercial durante el per\u00edodo de la promoci\u00f3n, esto es, <strong>del 3 al 18 de octubre de 2025<\/strong>, ambos inclusive. En ning\u00fan caso se aceptar\u00e1n tickets sin mostrar el producto comprado.<\/p>\n<p>Por cada entrega de uno o dos tickets que sumen un m\u00ednimo de 40\u20ac en el Punto de Informaci\u00f3n, acompa\u00f1ado por el producto comprado en el Centro Comercial, <strong>el cliente deber\u00e1 facilitar sus datos personales para obtener su participaci\u00f3n en el sorteo semanal<\/strong> a la azafata del Punto de Informaci\u00f3n de Espai Giron\u00e8s.<\/p>\n<p>Los tickets de compra deben corresponder a compras realizadas en tiendas o establecimientos abiertos al p\u00fablico del Centro Comercial durante el per\u00edodo de la promoci\u00f3n, esto es, <u>del 3 al 18 de octubre de 2025<\/u>, ambos inclusive. Quedan excluidas de la promoci\u00f3n las compras realizadas en el establecimiento de Loter\u00edas. Los tickets de restauraci\u00f3n deber\u00e1n ser sellados por el establecimiento en cuesti\u00f3n para poder ser aceptados en la promoci\u00f3n.<\/p>\n<p>No se aceptar\u00e1n, en ning\u00fan caso, tickets defectuosos en los que no se pueda leer la fecha de compra o cualquier otro dato relevante. Tampoco los que presenten signos evidentes de haber sido manipulados, cogidos de la basura, o en mal estado. Si la compra ha sido efectuada con tarjeta deber\u00e1 acompa\u00f1arse, junto con el ticket, el correspondiente resguardo bancario.<\/p>\n<p><strong>Los clientes podr\u00e1n participar tantas veces como deseen<\/strong> presentando en cada caso uno o dos tickets que sumen un m\u00ednimo de 40\u20ac, sin m\u00e1s limitaciones que las establecidas en las presentes Bases.<\/p>\n<p>Para participar en la promoci\u00f3n los clientes deber\u00e1n seguir el siguiente procedimiento:<\/p>\n<ul>\n<li>presentar los tickets de compra a la azafata del Punto de Informaci\u00f3n;<\/li>\n<li>la azafata comprobar\u00e1 que las compras corresponden a tiendas del Centro Comercial y dentro del per\u00edodo de la promoci\u00f3n, que no corresponden a compras efectuadas en el establecimiento de Loter\u00edas y que el importe de cada uno o dos tickets sumen un m\u00ednimo de 40 euros, y comprobar\u00e1 que lleven los productos comprados.<\/li>\n<li>la azafata marcar\u00e1 todos los tickets con un sello de Espai Giron\u00e8s,<strong> quedando invalidados para su reutilizaci\u00f3n<\/strong>;<\/li>\n<li>La azafata solicitar\u00e1 los siguientes datos al cliente para poder participar en la promoci\u00f3n:<\/li>\n<li>Nombre y apellidos<\/li>\n<li>DNI<\/li>\n<li>Tel\u00e9fono de contacto del cliente<\/li>\n<li>C\u00f3digo postal y provincia<\/li>\n<li>Email<\/li>\n<li>Importe de la\/s compra\/s<\/li>\n<li>Tiendas en las que han comprado<\/li>\n<li>Consentimiento para el env\u00edo para futuras acciones y\/o promociones del centro comercial<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Los sorteos de los premios se celebrar\u00e1n el lunes 13 de octubre, <\/strong>entre las personas que hayan participado del 3 al 10 de octubre,<strong> y el lunes 20 de octubre, <\/strong>entre las personas que hayan participado entre el 11 y el 18 de octubre.<\/p>\n<p>Se realizar\u00e1n de manera aleatoria a trav\u00e9s de una aplicaci\u00f3n inform\u00e1tica. Se contactar\u00e1 directamente con los premiados ese mismo d\u00eda <strong>mediante la direcci\u00f3n de correo electr\u00f3nico o tel\u00e9fono<\/strong> que hayan facilitado en el Punto de Informaci\u00f3n.<\/p>\n<p><strong>En cada sorteo se regalar\u00e1: <\/strong>2 packs para 2 personas con acceso al spa, masaje y una comida en el restaurante del centro l\u00fadico termal Magma de Santa Coloma de Farners, 1 visita guiada VIP para 4 personas por espacios interiores del Aquarium Oniria de Canet-en-Roussillon (sur de Francia) y 2 packs de entradas familiares (2 adultos + 2 ni\u00f1os o 2 adultos + 2 adultos) para el Aquarium Oniria de Canet-en-Roussillon (sur de Francia).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Las participaciones no son acumulativas por semanas,<\/strong> por lo que, si en la primera semana no se ha resultado premiado en el sorteo que corresponde, se deber\u00e1 volver a participar con nuevos tickets que sumen un m\u00ednimo de 40\u20ac para entrar en el segundo sorteo. Es decir, las personas inscritas del 3 al 10 de octubre solo ser\u00e1n contabilizadas para el sorteo que se realice el 13 de octubre, y as\u00ed sucesivamente.<\/p>\n<p>&nbsp;<\/p>\n<p>Con anterioridad a la entrega del premio, se comprobar\u00e1n los datos personales del premiado mediante la presentaci\u00f3n del DNI o documento acreditativo que permita verificar la autenticidad de los datos. Se extraer\u00e1 otros nombres m\u00e1s como suplentes, que ser\u00e1n utilizados en el supuesto de que las personas ganadoras no puedan disfrutar del premio en las condiciones antes indicadas y en el plazo especificado, o los datos no sean correctos.<\/p>\n<p>Los premiados ser\u00e1n convocados en las oficinas de gerencia <strong>durante la misma semana en la que se les comunique ganadores del sorteo<\/strong>:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Para el sorteo del 13 de octubre: entre el 13 y el 17 de octubre<\/li>\n<li>Para el sorteo del 20 de octubre: entre el 20 y el 24 de octubre<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>De este modo, se les podr\u00e1 hacer entrega de sus respectivos premios (packs Magma para 2 personas con acceso al spa, masaje y una comida en el restaurante del centro l\u00fadico termal Magma de Santa Coloma de Farners, visitas guiadas VIP para 4 personas por espacios interiores del Aquarium Oniria de Canet-en-Roussillon (sur de Francia) y packs de entradas familiares (2 adultos + 2 ni\u00f1os o 2 adultos + 2 adultos) para el Aquarium Oniria de Canet-en-Roussillon (sur de Francia). <strong>En total habr\u00e1 10 ganadores.<\/strong><\/p>\n<p><strong>Ser\u00e1 obligatorio que el premiado asista a dicha recogida con su DNI y con el n\u00famero o n\u00fameros que se le entregaron en el momento de participar.<\/strong> En caso de fuerza mayor (operaci\u00f3n, enfermedad o trabajo), si el premiado no puede asistir, podr\u00e1 venir en su lugar un familiar que deber\u00e1 llevar la siguiente documentaci\u00f3n:<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Fotocopia del DNI del premiado.<\/li>\n<li>Justificante (m\u00e9dico o trabajo) del premiado.<\/li>\n<li>Autorizaci\u00f3n firmada por parte del premiado.<\/li>\n<\/ol>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><u>7. Condiciones de participaci\u00f3n<\/u><\/strong><\/p>\n<p>La participaci\u00f3n en esta promoci\u00f3n supone la plena y total aceptaci\u00f3n de las bases descritas. En caso de discrepancias, prevalecer\u00e1 el criterio del organizador de la promoci\u00f3n. Asimismo, el Centro Comercial se reserva el derecho de resolver, seg\u00fan su interpretaci\u00f3n, los aspectos no previstos en estas bases.<\/p>\n<p>Cualquier manifestaci\u00f3n de no aceptaci\u00f3n de las condiciones de la promoci\u00f3n supondr\u00e1 la exclusi\u00f3n de la persona participante. El Centro Comercial se reserva el derecho de excluir a las personas participantes que por su conducta interfieran en el buen funcionamiento de la promoci\u00f3n.<\/p>\n<p>El Centro Comercial se reserva el derecho de eliminar a cualquier participante que defraude, altere o inutilice el buen funcionamiento y el transcurso reglamentario de la presente promoci\u00f3n, y en especial el de aquellos participantes en los que se evidencie o sospeche una actuaci\u00f3n irregular o fraudulenta.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>8.Derechos de imagen<\/u><\/strong><\/p>\n<p>Dado el fin estrictamente publicitario de la presente promoci\u00f3n, la imagen, nombre y voz de los ganadores podr\u00e1n ser utilizados a los efectos de informar sobre el resultado de dicha promoci\u00f3n, as\u00ed como respecto de ulteriores eventos de similar naturaleza en los medios de comunicaci\u00f3n que la sociedad Girona Retail Property S.L. estime necesarios (incluyendo, a t\u00edtulo de ejemplo, prensa, radio, televisi\u00f3n o Internet). Dicha cesi\u00f3n se realizar\u00e1 durante un plazo indefinido de tiempo y con \u00e1mbito territorial de Espa\u00f1a.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>9.Causas de descalificaci\u00f3n de un participante de la promoci\u00f3n<\/u><\/strong><\/p>\n<p>Esta promoci\u00f3n se organiza con la pretensi\u00f3n de incentivar y fomentar la participaci\u00f3n de todos los clientes del centro comercial \u201cEspai Giron\u00e8s\u201d, premiando la fidelidad en condiciones de igualdad y con estricto respeto al principio general de la buena fe. Por ese motivo, el Centro Comercial excluir\u00e1 autom\u00e1tica e inmediatamente de la misma a cualquier participante que transgreda las normas de la buena fe, observe una conducta mendaz o inadecuada, emplee medios fraudulentos o incumpla estas bases en cualquiera de sus extremos.<\/p>\n<p>En caso de que las irregularidades se detecten con posterioridad a la entrega efectiva de alguno de los premios, el Centro Comercial se reserva el derecho de ejercitar las acciones legales pertinentes contra su autor o responsable, entre otras, las tendentes a la devoluci\u00f3n de los premios.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>10.Tratamiento de Datos Personales<\/u><\/strong><\/p>\n<p>De conformidad con lo dispuesto en el Reglamento (UE) 2016\/679 de 27 de abril (GDPR) y la Ley Org\u00e1nica 3\/2018 de 5 de diciembre (LOPDGDD), los datos personales recogidos ser\u00e1n incorporados a un fichero registrado por la sociedad Girona Retail Property S.L., para la gesti\u00f3n de la presente promoci\u00f3n y el env\u00edo por correo ordinario o electr\u00f3nico de comunicaciones comerciales o promocionales del Centro Comercial.<\/p>\n<p>Aceptando las bases de la promoci\u00f3n \u201cGuanya packs Magma i visites a l\u2019aqu\u00e0rium Oniria\u201d, la empresa gestora mencionada arriba podr\u00e1 enviarle por los medios antes indicados informaci\u00f3n promocional sobre los productos y servicios de los titulares de los establecimientos comerciales ubicados en el indicado Centro Comercial, dedicados a la venta o prestaci\u00f3n de bienes o servicios de consumo. Puede consultar la relaci\u00f3n de dichos establecimientos y sus actividades en las Oficinas de Gerencia del Centro Comercial.<\/p>\n<p>Para el ejercicio de sus derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n y oposici\u00f3n deber\u00e1 dirigirse por escrito que le identifique a la sociedad Girona Retail Property S.L., con CIF B-13991187 y domicilio social en C\/Nanclares de Oca 1B, 28022 Madrid (Madrid). Si considera que el tratamiento no se ajusta a la normativa vigente, podr\u00e1 presentar una reclamaci\u00f3n ante la autoridad de control en <a href=\"http:\/\/www.aepd.es\">www.aepd.es<\/a>.<\/p>\n<p>La negativa a proporcionar los datos calificados como obligatorios implicar\u00e1 la imposibilidad de participar en la promoci\u00f3n. Asimismo, podr\u00e1n solicitarse otros datos de modo voluntario, con el objetivo de conocer mejor a los participantes de nuestras promociones y ofrecerles mejores productos y servicios.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>PROTECCI\u00d3N DE DATOS Y CONSENTIMIENTO DE CESI\u00d3N DE IM\u00c1GENES<\/u><\/strong><\/p>\n<p>Aceptando las condiciones de la promoci\u00f3n \u201cGuanya packs Magma i visites a l\u2019aqu\u00e0rium Oniria\u201d y la pol\u00edtica de protecci\u00f3n de datos de la misma, las personas que env\u00eden sus datos estar\u00e1n ofreciendo su consentimiento a:<\/p>\n<p>&nbsp;<\/p>\n<p>Consiento a que Girona Retail Property S.L. utilice mis datos a los efectos de gestionar mi participaci\u00f3n en la campa\u00f1a \u201cGuanya packs Magma i visites a l\u2019aqu\u00e0rium Oniria\u201d realizada en el Centro Comercial \u201cEspai Giron\u00e8s\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Consiento la toma de fotograf\u00edas y la grabaci\u00f3n de mi imagen y voz en el marco de la campa\u00f1a \u201cGuanya packs Magma i visites a l\u2019aqu\u00e0rium Oniria\u201d, as\u00ed como su posterior difusi\u00f3n a trav\u00e9s de redes sociales, web y otros medios de comunicaci\u00f3n, con la finalidad de divulgar las actividades que lleva a cabo el Centro Comercial \u201cEspai Giron\u00e8s\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Consiento que Girona Retail Property S.L. utilice mis datos para la realizaci\u00f3n de prospecciones comerciales en relaci\u00f3n con los clientes del Centro Comercial \u201cEspai Giron\u00e8s\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>De conformidad con lo dispuesto en el Reglamento (UE) 2016\/679 de 27 de abril (GDPR) y la Ley Org\u00e1nica 3\/2018 de 5 de diciembre (LOPDGDD), los datos personales recogidos ser\u00e1n incorporados a un fichero registrado por la sociedad Girona Retail Property S.L., para la gesti\u00f3n de la presente promoci\u00f3n y el env\u00edo por correo ordinario o electr\u00f3nico de comunicaciones comerciales o promocionales del Centro Comercial.<\/p>\n<p>Para el ejercicio de sus derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n y oposici\u00f3n deber\u00e1 dirigirse por escrito que le identifique a la sociedad Girona Retail Property S.L., con CIF B-13991187 y domicilio social en C\/Nanclares de Oca 1B, 28022 Madrid (Madrid). Si considera que el tratamiento no se ajusta a la normativa vigente, podr\u00e1 presentar una reclamaci\u00f3n ante la autoridad de control en <a href=\"http:\/\/www.aepd.es\">www.aepd.es<\/a>.<\/p>\n<p>La negativa a proporcionar los datos calificados como obligatorios implicar\u00e1 la imposibilidad de participar en la promoci\u00f3n. Asimismo, podr\u00e1n solicitarse otros datos de modo voluntario, con el objetivo de conocer mejor a los participantes de nuestras promociones y ofrecerles mejores productos y servicios.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":38316,"template":"","class_list":["post-38323","events","type-events","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gana packs Magma y visitas al acuario Oniria - Espai Giron\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gana packs Magma y visitas al acuario Oniria - Espai Giron\u00e8s\" \/>\n<meta property=\"og:description\" content=\"BASES &nbsp; 1.Finalidad de la promoci\u00f3n La presente promoci\u00f3n tiene por objeto incentivar las compras en los establecimientos del centro comercial Espai Giron\u00e8s mediante una campa\u00f1a de promoci\u00f3n de ventas. Para participar los visitantes deber\u00e1n entregar uno o dos tickets que sumen un m\u00ednimo de 40\u20ac en el Punto de Informaci\u00f3n para entrar en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/\" \/>\n<meta property=\"og:site_name\" content=\"Espai Giron\u00e8s\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T12:05:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.espaigirones.com\/wp-content\/uploads\/sites\/11\/2025\/10\/BannerWeb-1920x910-1-e1759759276622.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"910\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/\",\"url\":\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/\",\"name\":\"Gana packs Magma y visitas al acuario Oniria - Espai Giron\u00e8s\",\"isPartOf\":{\"@id\":\"https:\/\/www.espaigirones.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.espaigirones.com\/wp-content\/uploads\/sites\/11\/2025\/10\/BannerWeb-1920x910-1-e1759759276622.jpg\",\"datePublished\":\"2025-10-02T14:40:52+00:00\",\"dateModified\":\"2025-10-07T12:05:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#primaryimage\",\"url\":\"https:\/\/www.espaigirones.com\/wp-content\/uploads\/sites\/11\/2025\/10\/BannerWeb-1920x910-1-e1759759276622.jpg\",\"contentUrl\":\"https:\/\/www.espaigirones.com\/wp-content\/uploads\/sites\/11\/2025\/10\/BannerWeb-1920x910-1-e1759759276622.jpg\",\"width\":1920,\"height\":910},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Events\",\"item\":\"https:\/\/www.espaigirones.com\/events\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gana packs Magma y visitas al acuario Oniria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.espaigirones.com\/#website\",\"url\":\"https:\/\/www.espaigirones.com\/\",\"name\":\"Espai Giron\u00e8s\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.espaigirones.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gana packs Magma y visitas al acuario Oniria - Espai Giron\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/","og_locale":"es_ES","og_type":"article","og_title":"Gana packs Magma y visitas al acuario Oniria - Espai Giron\u00e8s","og_description":"BASES &nbsp; 1.Finalidad de la promoci\u00f3n La presente promoci\u00f3n tiene por objeto incentivar las compras en los establecimientos del centro comercial Espai Giron\u00e8s mediante una campa\u00f1a de promoci\u00f3n de ventas. Para participar los visitantes deber\u00e1n entregar uno o dos tickets que sumen un m\u00ednimo de 40\u20ac en el Punto de Informaci\u00f3n para entrar en el [&hellip;]","og_url":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/","og_site_name":"Espai Giron\u00e8s","article_modified_time":"2025-10-07T12:05:37+00:00","og_image":[{"width":1920,"height":910,"url":"https:\/\/www.espaigirones.com\/wp-content\/uploads\/sites\/11\/2025\/10\/BannerWeb-1920x910-1-e1759759276622.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/","url":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/","name":"Gana packs Magma y visitas al acuario Oniria - Espai Giron\u00e8s","isPartOf":{"@id":"https:\/\/www.espaigirones.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#primaryimage"},"image":{"@id":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.espaigirones.com\/wp-content\/uploads\/sites\/11\/2025\/10\/BannerWeb-1920x910-1-e1759759276622.jpg","datePublished":"2025-10-02T14:40:52+00:00","dateModified":"2025-10-07T12:05:37+00:00","breadcrumb":{"@id":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#primaryimage","url":"https:\/\/www.espaigirones.com\/wp-content\/uploads\/sites\/11\/2025\/10\/BannerWeb-1920x910-1-e1759759276622.jpg","contentUrl":"https:\/\/www.espaigirones.com\/wp-content\/uploads\/sites\/11\/2025\/10\/BannerWeb-1920x910-1-e1759759276622.jpg","width":1920,"height":910},{"@type":"BreadcrumbList","@id":"https:\/\/www.espaigirones.com\/es\/events\/guanya-packs-magma-i-visites-a-laquarium-oniria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Events","item":"https:\/\/www.espaigirones.com\/events\/"},{"@type":"ListItem","position":2,"name":"Gana packs Magma y visitas al acuario Oniria"}]},{"@type":"WebSite","@id":"https:\/\/www.espaigirones.com\/#website","url":"https:\/\/www.espaigirones.com\/","name":"Espai Giron\u00e8s","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.espaigirones.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.espaigirones.com\/es\/wp-json\/wp\/v2\/events\/38323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.espaigirones.com\/es\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/www.espaigirones.com\/es\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.espaigirones.com\/es\/wp-json\/wp\/v2\/media\/38316"}],"wp:attachment":[{"href":"https:\/\/www.espaigirones.com\/es\/wp-json\/wp\/v2\/media?parent=38323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}